{"id":90,"date":"2021-02-02T10:51:31","date_gmt":"2021-02-02T09:51:31","guid":{"rendered":"http:\/\/nivelgar.es\/?page_id=90"},"modified":"2021-03-23T19:43:01","modified_gmt":"2021-03-23T18:43:01","slug":"inicio","status":"publish","type":"page","link":"https:\/\/nivelgar.es\/","title":{"rendered":"Inicio"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbHeader\u00bb _builder_version=\u00bb4.8.2&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_start=\u00bb#000000&#8243; background_color_gradient_end=\u00bb#ffffff\u00bb background_color_gradient_start_position=\u00bb16%\u00bb background_color_gradient_end_position=\u00bb90%\u00bb background_image=\u00bbhttp:\/\/nivelgar.es\/wp-content\/uploads\/2021\/02\/1611168858H2N-DP-24Vacsense-fons.png\u00bb min_height=\u00bb200px\u00bb overflow-x=\u00bbhidden\u00bb overflow-y=\u00bbhidden\u00bb custom_padding=\u00bb41px||0px|||\u00bb bottom_divider_style=\u00bbslant\u00bb bottom_divider_color=\u00bb#ffffff\u00bb bottom_divider_height=\u00bb57vw\u00bb bottom_divider_flip=\u00bbhorizontal\u00bb background_last_edited=\u00bboff|desktop\u00bb locked=\u00bboff\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb3.26.2&#8243; custom_padding=\u00bb0px|||||\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb3.26.2&#8243;][et_pb_text _builder_version=\u00bb3.27.4&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb17px\u00bb text_line_height=\u00bb1.8em\u00bb header_2_font=\u00bbHeebo|500|||||||\u00bb header_2_font_size=\u00bb60px\u00bb header_2_line_height=\u00bb1.1em\u00bb background_layout=\u00bbdark\u00bb max_width=\u00bb800px\u00bb text_font_size_tablet=\u00bb17px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb24px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb]<\/p>\n<h2>NIVELGAR<\/h2>\n<p>Controles de nivel para l\u00edquidos conductores<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb3.26.2&#8243;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb3.26.2&#8243; locked=\u00bboff\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb3.26.2&#8243; background_color=\u00bb#ffffff\u00bb custom_padding=\u00bb40px|40px|40px|40px|true|true\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb|20px||20px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb link_option_url=\u00bb#\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb26px\u00bb box_shadow_blur=\u00bb90px\u00bb box_shadow_spread=\u00bb-14px\u00bb box_shadow_color=\u00bbrgba(0,71,214,0.18)\u00bb box_shadow_vertical__hover=\u00bb10px\u00bb box_shadow_vertical__hover_enabled=\u00bboff\u00bb box_shadow_blur__hover=\u00bb20px\u00bb box_shadow_blur__hover_enabled=\u00bboff\u00bb box_shadow_color__hover=\u00bb#2585b2&#8243; transform_styles__hover_enabled=\u00bbon\u00bb transform_scale__hover_enabled=\u00bbon\u00bb transform_translate__hover_enabled=\u00bbon\u00bb transform_rotate__hover_enabled=\u00bbon\u00bb transform_skew__hover_enabled=\u00bbon\u00bb transform_origin__hover_enabled=\u00bbon\u00bb transform_scale__hover=\u00bb107%|107%\u00bb][et_pb_blurb title=\u00bbGran resistencia\u00bb image=\u00bbhttp:\/\/nivelgar.es\/wp-content\/uploads\/2021\/02\/icons8-electricidad-50.png\u00bb _builder_version=\u00bb4.8.2&#8243; header_font=\u00bbHeebo|800|||||||\u00bb header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||76px|||\u00bb header_font_size_tablet=\u00bb15px\u00bb header_font_size_phone=\u00bb14px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bboff|phone\u00bb locked=\u00bboff\u00bb]<\/p>\n<p><span>Gran resistencia a sobre-tensiones, producidas por tormentas, ya comprobada desde los numerosos a\u00f1os de utilizaci\u00f3n.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb3.26.2&#8243; background_color=\u00bb#ffffff\u00bb custom_padding=\u00bb40px|40px|40px|40px|true|true\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb|20px||20px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb link_option_url=\u00bb#\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb26px\u00bb box_shadow_blur=\u00bb90px\u00bb box_shadow_spread=\u00bb-14px\u00bb box_shadow_color=\u00bbrgba(0,71,214,0.18)\u00bb box_shadow_vertical__hover=\u00bb10px\u00bb box_shadow_vertical__hover_enabled=\u00bboff\u00bb box_shadow_blur__hover=\u00bb20px\u00bb box_shadow_blur__hover_enabled=\u00bboff\u00bb box_shadow_color__hover=\u00bb#2585b2&#8243; transform_styles__hover_enabled=\u00bbon\u00bb transform_scale__hover_enabled=\u00bbon\u00bb transform_translate__hover_enabled=\u00bbon\u00bb transform_rotate__hover_enabled=\u00bbon\u00bb transform_skew__hover_enabled=\u00bbon\u00bb transform_origin__hover_enabled=\u00bbon\u00bb transform_scale__hover=\u00bb107%|107%\u00bb][et_pb_blurb title=\u00bbLarga distancia\u00bb image=\u00bbhttp:\/\/nivelgar.es\/wp-content\/uploads\/2021\/02\/icons8-arreglar-de-nuevo-50.png\u00bb _builder_version=\u00bb4.8.2&#8243; header_font=\u00bbHeebo|800|||||||\u00bb header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb header_font_size_tablet=\u00bb15px\u00bb header_font_size_phone=\u00bb14px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bboff|phone\u00bb locked=\u00bboff\u00bb]<\/p>\n<p><span>\u00danica marca en el mercado nacional, cuyos equipos pueden trabajar a gran distancia de las sondas, llegando as\u00ed hasta 3 Km en versi\u00f3n normal, y en versi\u00f3n especial hasta 7 Km o m\u00e1s<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb3.26.2&#8243; background_color=\u00bb#ffffff\u00bb custom_padding=\u00bb40px|40px|40px|40px|true|true\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb|20px||20px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb link_option_url=\u00bb#\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb26px\u00bb box_shadow_blur=\u00bb90px\u00bb box_shadow_spread=\u00bb-14px\u00bb box_shadow_color=\u00bbrgba(0,71,214,0.18)\u00bb box_shadow_vertical__hover=\u00bb10px\u00bb box_shadow_vertical__hover_enabled=\u00bboff\u00bb box_shadow_blur__hover=\u00bb20px\u00bb box_shadow_blur__hover_enabled=\u00bboff\u00bb box_shadow_color__hover=\u00bb#2585b2&#8243; transform_styles__hover_enabled=\u00bbon\u00bb transform_scale__hover_enabled=\u00bbon\u00bb transform_translate__hover_enabled=\u00bbon\u00bb transform_rotate__hover_enabled=\u00bbon\u00bb transform_skew__hover_enabled=\u00bbon\u00bb transform_origin__hover_enabled=\u00bbon\u00bb transform_scale__hover=\u00bb107%|107%\u00bb][et_pb_blurb title=\u00bbVentajas\u00bb image=\u00bbhttp:\/\/nivelgar.es\/wp-content\/uploads\/2021\/02\/icons8-monedas-50.png\u00bb image_max_width=\u00bb77%\u00bb _builder_version=\u00bb4.8.2&#8243; header_font=\u00bbHeebo|800|||||||\u00bb header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb min_height=\u00bb338px\u00bb custom_margin=\u00bb0px||||false|false\u00bb custom_padding=\u00bb||28px|||\u00bb header_font_size_tablet=\u00bb15px\u00bb header_font_size_phone=\u00bb14px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bboff|phone\u00bb locked=\u00bboff\u00bb]<\/p>\n<p><span>Ventajas t\u00e9cnicas y econ\u00f3micas en la venta del conjunto de sonda y peso.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb3.26.2&#8243; background_color=\u00bb#ffffff\u00bb custom_padding=\u00bb40px|40px|40px|40px|true|true\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb|20px||20px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb link_option_url=\u00bb#\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb26px\u00bb box_shadow_blur=\u00bb90px\u00bb box_shadow_spread=\u00bb-14px\u00bb box_shadow_color=\u00bbrgba(0,71,214,0.18)\u00bb box_shadow_vertical__hover=\u00bb10px\u00bb box_shadow_vertical__hover_enabled=\u00bboff\u00bb box_shadow_blur__hover=\u00bb20px\u00bb box_shadow_blur__hover_enabled=\u00bboff\u00bb box_shadow_color__hover=\u00bb#2585b2&#8243; transform_styles__hover_enabled=\u00bbon\u00bb transform_scale__hover_enabled=\u00bbon\u00bb transform_translate__hover_enabled=\u00bbon\u00bb transform_rotate__hover_enabled=\u00bbon\u00bb transform_skew__hover_enabled=\u00bbon\u00bb transform_origin__hover_enabled=\u00bbon\u00bb transform_scale__hover=\u00bb107%|107%\u00bb][et_pb_blurb title=\u00bbServicio Post Venta\u00bb image=\u00bbhttp:\/\/nivelgar.es\/wp-content\/uploads\/2021\/02\/icons8-solicitar-servicio-50.png\u00bb _builder_version=\u00bb4.8.2&#8243; header_font=\u00bbHeebo|800|||||||\u00bb header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb min_height=\u00bb337px\u00bb header_font_size_tablet=\u00bb15px\u00bb header_font_size_phone=\u00bb14px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bboff|phone\u00bb locked=\u00bboff\u00bb]<\/p>\n<p><span>Servicio post-venta en el que contempla consultas t\u00e9cnicas y posibles reparaciones de los equipos, juntamente con sus esquemas de montaje.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbMission\u00bb _builder_version=\u00bb3.26.2&#8243;][et_pb_row column_structure=\u00bb1_2,1_2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.8.2&#8243; background_color=\u00bbrgba(255,255,255,0.63)\u00bb custom_margin=\u00bb56px|auto|56px|auto|true|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb26px\u00bb box_shadow_blur=\u00bb90px\u00bb box_shadow_spread=\u00bb-14px\u00bb box_shadow_color=\u00bbrgba(0,71,214,0.18)\u00bb locked=\u00bboff\u00bb box_shadow_vertical__hover=\u00bb10px\u00bb box_shadow_vertical__hover_enabled=\u00bboff\u00bb box_shadow_blur__hover=\u00bb20px\u00bb box_shadow_blur__hover_enabled=\u00bboff\u00bb box_shadow_color__hover=\u00bb#2585b2&#8243;][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.8.2&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_start=\u00bb#701503&#8243; background_color_gradient_end=\u00bb#a34532&#8243; background_color_gradient_direction=\u00bb181deg\u00bb background_color_gradient_start_position=\u00bb66%\u00bb custom_padding=\u00bb18vw|60px|18vw|60px|true|true\u00bb custom_padding_tablet=\u00bb40px|30px|40px|30px|true|true\u00bb custom_padding_phone=\u00bb30px|20px|30px|20px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb][et_pb_text _builder_version=\u00bb4.9.0&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb17px\u00bb text_line_height=\u00bb1.8em\u00bb header_2_font=\u00bbHeebo|300|||||||\u00bb header_2_font_size=\u00bb70px\u00bb background_layout=\u00bbdark\u00bb custom_padding=\u00bb|||6px||\u00bb text_font_size_tablet=\u00bb17px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb60px\u00bb header_2_font_size_phone=\u00bb36px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb]<\/p>\n<h2 style=\"text-align: left;\">NUEVA <strong>SERIE H<\/strong><\/h2>\n<blockquote>\n<h3><em>Tiene una t\u00e9cnica innovadora y dispone de m\u00e1s prestaciones que ser\u00e1n muy apreciadas a lo largo de la vida de la instalaci\u00f3n.<\/em><\/h3>\n<\/blockquote>\n<p>Proporcionando facilidad en la instalaci\u00f3n, en el montaje, y en las pruebas de funionamiento que desee efectuar el instalador; el cual ahorrar\u00e1 tiempo muerto al instalador, y un funcionamiento agradable y muy fiable para el cliente, que le dar\u00e1n una tranquilidad al cliente a lo largo de su periodo de trabajo.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.8.2&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_blurb title=\u00bbDOBLE SENSIBILIDAD\u00bb icon_placement=\u00bbleft\u00bb image_max_width=\u00bb100px\u00bb _builder_version=\u00bb4.8.2&#8243; header_font=\u00bbHeebo|800|||||||\u00bb header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb max_width=\u00bb400px\u00bb header_font_size_tablet=\u00bb15px\u00bb header_font_size_phone=\u00bb14px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bboff|phone\u00bb locked=\u00bboff\u00bb]<\/p>\n<p><span style=\"font-size: 16px;\">Doble sensibilidad para poder ajustar mejor el elctronivel a las necesidades y a la dureza que tengan los l\u00edquidos. Si hablamos de agua, se podr\u00e1 ajustar mejor la sensibilidad de bombeo de las aguas duras y blandas, de costa y de monta\u00f1a; e incluso finci\u00f3n en fosas s\u00e9pticas o aguas residuales o l\u00edquidos de diferente conductividad.<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbPULSADORES\u00bb icon_placement=\u00bbleft\u00bb image_max_width=\u00bb100px\u00bb _builder_version=\u00bb4.8.2&#8243; header_font=\u00bbHeebo|800|||||||\u00bb header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb max_width=\u00bb400px\u00bb header_font_size_tablet=\u00bb15px\u00bb header_font_size_phone=\u00bb14px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bboff|phone\u00bb locked=\u00bboff\u00bb]<\/p>\n<p>Pulsadores que activan las sondas y adelantan la maniobra, tanto el arranque de la bomba en el pozo, como el paro del dep\u00f3sito.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbGRAN RESISTENCIA A LAS TORMENTAS\u00bb icon_placement=\u00bbleft\u00bb image_max_width=\u00bb100px\u00bb _builder_version=\u00bb4.8.2&#8243; header_font=\u00bbHeebo|800|||||||\u00bb header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb max_width=\u00bb400px\u00bb header_font_size_tablet=\u00bb15px\u00bb header_font_size_phone=\u00bb14px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bboff|phone\u00bb locked=\u00bboff\u00bb]<\/p>\n<p>Protecci\u00f3n contra el 90% de arm\u00f3nico el\u00e9ctricos<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbINSTALACI\u00d3N A GRAN LONGITUD\u00bb icon_placement=\u00bbleft\u00bb image_max_width=\u00bb100px\u00bb _builder_version=\u00bb4.8.2&#8243; header_font=\u00bbHeebo|800|||||||\u00bb header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb max_width=\u00bb400px\u00bb header_font_size_tablet=\u00bb15px\u00bb header_font_size_phone=\u00bb14px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bboff|phone\u00bb locked=\u00bboff\u00bb]<\/p>\n<p>Se pueden instalar las sondas a gran longitud del equipo<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbSONDAS COMPATIBLES CON VARIOS REL\u00c9S\u00bb icon_placement=\u00bbleft\u00bb image_max_width=\u00bb100px\u00bb _builder_version=\u00bb4.8.2&#8243; header_font=\u00bbHeebo|800|||||||\u00bb header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb max_width=\u00bb400px\u00bb header_font_size_tablet=\u00bb15px\u00bb header_font_size_phone=\u00bb14px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bboff|phone\u00bb locked=\u00bboff\u00bb]<\/p>\n<p>La sonda com\u00fan n\u00ba 7 puede ser com\u00fan para varios rel\u00e9s que trabajen en el mismo contenedor; puenteando todos los bornes n\u00ba 7 de todos los rel\u00e9s y conectando el mismo a tierra<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbCONEXI\u00d3N INSTANT\u00c1NEA\u00bb icon_placement=\u00bbleft\u00bb image_max_width=\u00bb100px\u00bb _builder_version=\u00bb4.8.2&#8243; header_font=\u00bbHeebo|800|||||||\u00bb header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb max_width=\u00bb400px\u00bb header_font_size_tablet=\u00bb15px\u00bb header_font_size_phone=\u00bb14px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bboff|phone\u00bb locked=\u00bboff\u00bb]<\/p>\n<p>Todos los rel\u00e9s s\u00f3n enchufables a <strong>base undecal<\/strong>, conexi\u00f3n instant\u00e1nea.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFooter\u00bb _builder_version=\u00bb4.8.2&#8243; background_color=\u00bbRGBA(0,0,0,0)\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_start=\u00bb#edef69&#8243; background_color_gradient_end=\u00bb#ffffff\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb107px||0px|||\u00bb locked=\u00bboff\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.9.2&#8243; min_height=\u00bb583.1px\u00bb custom_padding=\u00bb||0px|||\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb3.26.2&#8243;][et_pb_text _builder_version=\u00bb4.8.2&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb17px\u00bb text_line_height=\u00bb1.8em\u00bb header_2_font=\u00bbHeebo|500|||||||\u00bb header_2_text_color=\u00bb#0a2d61&#8243; header_2_font_size=\u00bb60px\u00bb header_2_line_height=\u00bb1.1em\u00bb header_3_font=\u00bbHeebo|800|||||||\u00bb header_3_font_size=\u00bb28px\u00bb header_3_line_height=\u00bb1.2em\u00bb text_font_size_tablet=\u00bb17px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb24px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb header_3_font_tablet=\u00bbHeebo|700|||||||\u00bb header_3_font_phone=\u00bb\u00bb header_3_font_last_edited=\u00bbon|phone\u00bb header_3_font_size_tablet=\u00bb24px\u00bb header_3_font_size_phone=\u00bb18px\u00bb header_3_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb]<\/p>\n<h2>Contacta<\/h2>\n<p>NIVELGAR<\/p>\n<p>Av. Catalunya, 13 Bajos<\/p>\n<p>43830 Torredembarra<\/p>\n<p>[\/et_pb_text][et_pb_blurb title=\u00bb977 64 15 16&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb%%264%%\u00bb icon_color=\u00bb#0047d6&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb100%\u00bb use_icon_font_size=\u00bbon\u00bb icon_font_size=\u00bb24px\u00bb _builder_version=\u00bb4.8.2&#8243; header_font=\u00bbHeebo|800|||||||\u00bb header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.8em\u00bb text_orientation=\u00bbcenter\u00bb header_font_size_tablet=\u00bb15px\u00bb header_font_size_phone=\u00bb14px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_tablet=\u00bb\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.9.2&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_start=\u00bb#000000&#8243; background_color_gradient_end=\u00bb#000000&#8243; background_color_gradient_direction=\u00bb140deg\u00bb transform_scale_tablet=\u00bb\u00bb transform_scale_phone=\u00bb\u00bb transform_scale_last_edited=\u00bbon|desktop\u00bb transform_translate=\u00bb0px|-120px\u00bb transform_translate_tablet=\u00bb0px|0px\u00bb transform_translate_phone=\u00bb\u00bb transform_translate_last_edited=\u00bbon|phone\u00bb transform_translate_linked=\u00bboff\u00bb transform_rotate_tablet=\u00bb\u00bb transform_rotate_phone=\u00bb\u00bb transform_rotate_last_edited=\u00bbon|desktop\u00bb transform_skew_tablet=\u00bb\u00bb transform_skew_phone=\u00bb\u00bb transform_skew_last_edited=\u00bbon|desktop\u00bb transform_origin_tablet=\u00bb\u00bb transform_origin_phone=\u00bb\u00bb transform_origin_last_edited=\u00bbon|desktop\u00bb transform_styles_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb60px|30px|60px|30px|true|true\u00bb transform_styles_tablet=\u00bb\u00bb transform_styles_phone=\u00bb\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb26px\u00bb box_shadow_blur=\u00bb90px\u00bb box_shadow_spread=\u00bb-14px\u00bb box_shadow_color=\u00bb#1a8aed\u00bb box_shadow_vertical__hover=\u00bb10px\u00bb box_shadow_vertical__hover_enabled=\u00bboff\u00bb box_shadow_blur__hover=\u00bb20px\u00bb box_shadow_blur__hover_enabled=\u00bboff\u00bb box_shadow_color__hover=\u00bb#2585b2&#8243;][et_pb_contact_form captcha=\u00bboff\u00bb email=\u00bbgermanjr@nivelgar.es\u00bb title=\u00bbContacta con nosotros\u00bb success_message=\u00bbTu mensaje ha sido enviado, te responderemos lo m\u00e1s r\u00e1pido posible\u00bb module_id=\u00bbet_pb_contact_form_0&#8243; _builder_version=\u00bb4.9.2&#8243; form_field_background_color=\u00bbrgba(0,0,0,0)\u00bb form_field_text_color=\u00bb#ffffff\u00bb form_field_focus_background_color=\u00bbrgba(0,0,0,0)\u00bb form_field_custom_margin=\u00bb||30px||false|false\u00bb form_field_custom_padding=\u00bb|0px||0px|false|false\u00bb title_text_color=\u00bb#000000&#8243; form_field_font=\u00bbHeebo|500|||||||\u00bb background_color=\u00bb#FFFFFF\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_start=\u00bb#ffffff\u00bb background_color_gradient_end=\u00bb#ffffff\u00bb background_color_gradient_direction=\u00bb239deg\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#0047d6&#8243; button_bg_color=\u00bb#ffffff\u00bb button_bg_color_gradient_direction=\u00bb148deg\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb2px\u00bb button_font=\u00bbHeebo|700||on|||||\u00bb button_custom_padding=\u00bb15px|34px|15px|34px|true|true\u00bb custom_margin=\u00bb0px||||false|false\u00bb hover_enabled=\u00bb0&#8243; border_color_all=\u00bbrgba(0,71,214,0.37)\u00bb border_width_bottom=\u00bb2px\u00bb box_shadow_style=\u00bbpreset1&#8243; box_shadow_style_button=\u00bbpreset3&#8243; box_shadow_vertical_button=\u00bb10px\u00bb box_shadow_blur_button=\u00bb30px\u00bb box_shadow_spread_button=\u00bb-10px\u00bb box_shadow_color_button=\u00bbrgba(255,142,96,0.39)\u00bb locked=\u00bboff\u00bb sticky_enabled=\u00bb0&#8243; custom_message=\u00bbNombre: %%Name%%||et_pb_line_break_holder||Correo: %%Email%%||et_pb_line_break_holder||||et_pb_line_break_holder||%%Message%%\u00bb][et_pb_contact_field field_id=\u00bbName\u00bb field_title=\u00bbNombre\u00bb _builder_version=\u00bb4.9.2&#8243; form_field_text_color=\u00bb#000000&#8243; button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbEmail\u00bb field_title=\u00bbEmail\u00bb field_type=\u00bbemail\u00bb _builder_version=\u00bb4.9.2&#8243; form_field_text_color=\u00bb#000000&#8243; button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbMessage\u00bb field_title=\u00bbEsc\u00edbenos tus dudas\u00bb field_type=\u00bbtext\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.9.2&#8243; form_field_text_color=\u00bb#000000&#8243; button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NIVELGAR Controles de nivel para l\u00edquidos conductoresGran resistencia a sobre-tensiones, producidas por tormentas, ya comprobada desde los numerosos a\u00f1os de utilizaci\u00f3n.\u00danica marca en el mercado nacional, cuyos equipos pueden trabajar a gran distancia de las sondas, llegando as\u00ed hasta 3 Km en versi\u00f3n normal, y en versi\u00f3n especial hasta 7 Km o m\u00e1sVentajas t\u00e9cnicas y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-90","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inicio - Nivelgar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nivelgar.es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inicio - Nivelgar\" \/>\n<meta property=\"og:description\" content=\"NIVELGAR Controles de nivel para l\u00edquidos conductoresGran resistencia a sobre-tensiones, producidas por tormentas, ya comprobada desde los numerosos a\u00f1os de utilizaci\u00f3n.\u00danica marca en el mercado nacional, cuyos equipos pueden trabajar a gran distancia de las sondas, llegando as\u00ed hasta 3 Km en versi\u00f3n normal, y en versi\u00f3n especial hasta 7 Km o m\u00e1sVentajas t\u00e9cnicas y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nivelgar.es\/\" \/>\n<meta property=\"og:site_name\" content=\"Nivelgar\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-23T18:43:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nivelgar.es\\\/\",\"url\":\"https:\\\/\\\/nivelgar.es\\\/\",\"name\":\"Inicio - Nivelgar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nivelgar.es\\\/#website\"},\"datePublished\":\"2021-02-02T09:51:31+00:00\",\"dateModified\":\"2021-03-23T18:43:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nivelgar.es\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nivelgar.es\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nivelgar.es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nivelgar.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inicio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nivelgar.es\\\/#website\",\"url\":\"https:\\\/\\\/nivelgar.es\\\/\",\"name\":\"Nivelgar\",\"description\":\"Controles de Nivel\",\"publisher\":{\"@id\":\"https:\\\/\\\/nivelgar.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nivelgar.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nivelgar.es\\\/#organization\",\"name\":\"Electricitat i aplicacions German\",\"url\":\"https:\\\/\\\/nivelgar.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nivelgar.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nivelgar.es\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-nivelgar.jpg\",\"contentUrl\":\"https:\\\/\\\/nivelgar.es\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-nivelgar.jpg\",\"width\":400,\"height\":100,\"caption\":\"Electricitat i aplicacions German\"},\"image\":{\"@id\":\"https:\\\/\\\/nivelgar.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inicio - Nivelgar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nivelgar.es\/","og_locale":"es_ES","og_type":"article","og_title":"Inicio - Nivelgar","og_description":"NIVELGAR Controles de nivel para l\u00edquidos conductoresGran resistencia a sobre-tensiones, producidas por tormentas, ya comprobada desde los numerosos a\u00f1os de utilizaci\u00f3n.\u00danica marca en el mercado nacional, cuyos equipos pueden trabajar a gran distancia de las sondas, llegando as\u00ed hasta 3 Km en versi\u00f3n normal, y en versi\u00f3n especial hasta 7 Km o m\u00e1sVentajas t\u00e9cnicas y [&hellip;]","og_url":"https:\/\/nivelgar.es\/","og_site_name":"Nivelgar","article_modified_time":"2021-03-23T18:43:01+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nivelgar.es\/","url":"https:\/\/nivelgar.es\/","name":"Inicio - Nivelgar","isPartOf":{"@id":"https:\/\/nivelgar.es\/#website"},"datePublished":"2021-02-02T09:51:31+00:00","dateModified":"2021-03-23T18:43:01+00:00","breadcrumb":{"@id":"https:\/\/nivelgar.es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nivelgar.es\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nivelgar.es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nivelgar.es\/"},{"@type":"ListItem","position":2,"name":"Inicio"}]},{"@type":"WebSite","@id":"https:\/\/nivelgar.es\/#website","url":"https:\/\/nivelgar.es\/","name":"Nivelgar","description":"Controles de Nivel","publisher":{"@id":"https:\/\/nivelgar.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nivelgar.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nivelgar.es\/#organization","name":"Electricitat i aplicacions German","url":"https:\/\/nivelgar.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nivelgar.es\/#\/schema\/logo\/image\/","url":"https:\/\/nivelgar.es\/wp-content\/uploads\/2021\/02\/logo-nivelgar.jpg","contentUrl":"https:\/\/nivelgar.es\/wp-content\/uploads\/2021\/02\/logo-nivelgar.jpg","width":400,"height":100,"caption":"Electricitat i aplicacions German"},"image":{"@id":"https:\/\/nivelgar.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/nivelgar.es\/index.php\/wp-json\/wp\/v2\/pages\/90","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nivelgar.es\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nivelgar.es\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nivelgar.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nivelgar.es\/index.php\/wp-json\/wp\/v2\/comments?post=90"}],"version-history":[{"count":30,"href":"https:\/\/nivelgar.es\/index.php\/wp-json\/wp\/v2\/pages\/90\/revisions"}],"predecessor-version":[{"id":643,"href":"https:\/\/nivelgar.es\/index.php\/wp-json\/wp\/v2\/pages\/90\/revisions\/643"}],"wp:attachment":[{"href":"https:\/\/nivelgar.es\/index.php\/wp-json\/wp\/v2\/media?parent=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}